{"id":5392,"date":"2023-07-20T12:43:47","date_gmt":"2023-07-20T16:43:47","guid":{"rendered":"https:\/\/copernic.com\/?p=5392"},"modified":"2023-09-26T13:30:11","modified_gmt":"2023-09-26T17:30:11","slug":"comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic","status":"publish","type":"post","link":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/","title":{"rendered":"Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic"},"content":{"rendered":"\n<p>Cela arrive \u00e0 chacun d&rsquo;entre nous : nous travaillons sur un document, nous l&rsquo;enregistrons, nous oublions o\u00f9 nous l&rsquo;avons enregistr\u00e9 et nous l&rsquo;enregistrons \u00e0 nouveau dans un autre dossier de notre ordinateur. Nous avons alors plusieurs fichiers portant le m\u00eame nom dans notre liste de documents, ce qui cr\u00e9e une certaine confusion lorsque nous essayons de localiser le bon fichier.<\/p>\n\n\n\n<p>Copernic peut vous aider! Si vous souhaitez localiser tous les fichiers portant le m\u00eame nom afin de supprimer les documents superflus, il vous suffit de saisir le nom des documents dans la barre de recherche de la page du tableau de bord de Copernic :<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"936\" height=\"208\" src=\"https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/image-10.png\" alt=\"\" class=\"wp-image-5393\" srcset=\"https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/image-10.png 936w, https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/image-10-300x67.png 300w, https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/image-10-768x171.png 768w\" sizes=\"auto, (max-width: 936px) 100vw, 936px\" \/><\/figure>\n\n\n\n<p>Une fois que les doublons sont affich\u00e9s, cliquez sur celui que vous souhaitez supprimer ou sur lequel vous souhaitez travailler. En bas de l&rsquo;\u00e9cran, la pr\u00e9visualisation affiche l&rsquo;article. Sur le c\u00f4t\u00e9 droit, vous verrez un menu d\u00e9roulant. Vous pouvez s\u00e9lectionner l&rsquo;option de votre choix dans ce menu d\u00e9roulant.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"936\" height=\"356\" src=\"https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/image-11.png\" alt=\"\" class=\"wp-image-5395\" srcset=\"https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/image-11.png 936w, https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/image-11-300x114.png 300w, https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/image-11-768x292.png 768w\" sizes=\"auto, (max-width: 936px) 100vw, 936px\" \/><\/figure>\n\n\n\n<p>Nous suivez-vous sur les m\u00e9dias sociaux? Nous sommes pr\u00e9sents sur LinkedIn, Facebook et X (anciennement connu sous le nom Twitter). Suivez-nous pour des conseils amusants et des promotions! Vous pouvez joindre les membres de notre \u00e9quipe de soutien \u00e0 <a href=\"mailto:support@copernic.com\">support@copernic.com<\/a>.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cela arrive \u00e0 chacun d&rsquo;entre nous : nous travaillons sur un document, nous l&rsquo;enregistrons, nous oublions o\u00f9 nous l&rsquo;avons enregistr\u00e9 et nous l&rsquo;enregistrons \u00e0 nouveau dans un autre dossier de notre ordinateur. Nous avons alors plusieurs fichiers portant le m\u00eame nom dans notre liste de documents, ce qui cr\u00e9e une certaine confusion lorsque nous essayons&#8230;<\/p>\n","protected":false},"author":3,"featured_media":5333,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[22],"tags":[],"class_list":["post-5392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mode-demploi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic | Copernic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic | Copernic\" \/>\n<meta property=\"og:description\" content=\"Cela arrive \u00e0 chacun d&rsquo;entre nous : nous travaillons sur un document, nous l&rsquo;enregistrons, nous oublions o\u00f9 nous l&rsquo;avons enregistr\u00e9 et nous l&rsquo;enregistrons \u00e0 nouveau dans un autre dossier de notre ordinateur. Nous avons alors plusieurs fichiers portant le m\u00eame nom dans notre liste de documents, ce qui cr\u00e9e une certaine confusion lorsque nous essayons...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/\" \/>\n<meta property=\"og:site_name\" content=\"Copernic\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-20T16:43:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-26T17:30:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/Find-File.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1206\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R\u00f3mulo Oma\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"R\u00f3mulo Oma\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/\"},\"author\":{\"name\":\"R\u00f3mulo Oma\u00f1a\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/person\\\/7985327088d54ba4e291e8dc69713fe6\"},\"headline\":\"Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic\",\"datePublished\":\"2023-07-20T16:43:47+00:00\",\"dateModified\":\"2023-09-26T17:30:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/\"},\"wordCount\":221,\"publisher\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Find-File.jpeg\",\"articleSection\":[\"Mode d'emploi\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/\",\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/\",\"name\":\"Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic | Copernic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Find-File.jpeg\",\"datePublished\":\"2023-07-20T16:43:47+00:00\",\"dateModified\":\"2023-09-26T17:30:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Find-File.jpeg\",\"contentUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Find-File.jpeg\",\"width\":1206,\"height\":900,\"caption\":\"Laptop computer with magnifying glass.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2023\\\/07\\\/20\\\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/copernic.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/\",\"name\":\"Copernic\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/copernic.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#organization\",\"name\":\"Copernic\",\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo.png\",\"width\":238,\"height\":68,\"caption\":\"Copernic\"},\"image\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/person\\\/7985327088d54ba4e291e8dc69713fe6\",\"name\":\"R\u00f3mulo Oma\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g\",\"caption\":\"R\u00f3mulo Oma\u00f1a\"},\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/author\\\/romanacopernic-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic | Copernic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/","og_locale":"fr_CA","og_type":"article","og_title":"Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic | Copernic","og_description":"Cela arrive \u00e0 chacun d&rsquo;entre nous : nous travaillons sur un document, nous l&rsquo;enregistrons, nous oublions o\u00f9 nous l&rsquo;avons enregistr\u00e9 et nous l&rsquo;enregistrons \u00e0 nouveau dans un autre dossier de notre ordinateur. Nous avons alors plusieurs fichiers portant le m\u00eame nom dans notre liste de documents, ce qui cr\u00e9e une certaine confusion lorsque nous essayons...","og_url":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/","og_site_name":"Copernic","article_published_time":"2023-07-20T16:43:47+00:00","article_modified_time":"2023-09-26T17:30:11+00:00","og_image":[{"width":1206,"height":900,"url":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/Find-File.jpeg","type":"image\/jpeg"}],"author":"R\u00f3mulo Oma\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"R\u00f3mulo Oma\u00f1a","Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/#article","isPartOf":{"@id":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/"},"author":{"name":"R\u00f3mulo Oma\u00f1a","@id":"https:\/\/copernic.com\/fr\/#\/schema\/person\/7985327088d54ba4e291e8dc69713fe6"},"headline":"Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic","datePublished":"2023-07-20T16:43:47+00:00","dateModified":"2023-09-26T17:30:11+00:00","mainEntityOfPage":{"@id":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/"},"wordCount":221,"publisher":{"@id":"https:\/\/copernic.com\/fr\/#organization"},"image":{"@id":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/#primaryimage"},"thumbnailUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/Find-File.jpeg","articleSection":["Mode d'emploi"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/","url":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/","name":"Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic | Copernic","isPartOf":{"@id":"https:\/\/copernic.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/#primaryimage"},"image":{"@id":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/#primaryimage"},"thumbnailUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/Find-File.jpeg","datePublished":"2023-07-20T16:43:47+00:00","dateModified":"2023-09-26T17:30:11+00:00","breadcrumb":{"@id":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/#primaryimage","url":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/Find-File.jpeg","contentUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/Find-File.jpeg","width":1206,"height":900,"caption":"Laptop computer with magnifying glass."},{"@type":"BreadcrumbList","@id":"https:\/\/copernic.com\/fr\/2023\/07\/20\/comment-trouver-rapidement-les-doublons-avec-desktop-search-et-server-search-de-copernic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/copernic.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Comment trouver rapidement les doublons avec Desktop Search et Server Search de Copernic"}]},{"@type":"WebSite","@id":"https:\/\/copernic.com\/fr\/#website","url":"https:\/\/copernic.com\/fr\/","name":"Copernic","description":"","publisher":{"@id":"https:\/\/copernic.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/copernic.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/copernic.com\/fr\/#organization","name":"Copernic","url":"https:\/\/copernic.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/copernic.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/12\/logo.png","contentUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/12\/logo.png","width":238,"height":68,"caption":"Copernic"},"image":{"@id":"https:\/\/copernic.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/copernic.com\/fr\/#\/schema\/person\/7985327088d54ba4e291e8dc69713fe6","name":"R\u00f3mulo Oma\u00f1a","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g","caption":"R\u00f3mulo Oma\u00f1a"},"url":"https:\/\/copernic.com\/fr\/author\/romanacopernic-com\/"}]}},"taxonomy_info":{"category":[{"value":22,"label":"Mode d'emploi"}]},"featured_image_src_large":["https:\/\/copernic.com\/wp-content\/uploads\/2023\/08\/Find-File-1024x764.jpeg",1024,764,true],"author_info":{"display_name":"R\u00f3mulo Oma\u00f1a","author_link":"https:\/\/copernic.com\/fr\/author\/romanacopernic-com\/"},"comment_info":0,"category_info":[{"term_id":22,"name":"Mode d'emploi","slug":"mode-demploi","term_group":0,"term_taxonomy_id":22,"taxonomy":"category","description":"","parent":0,"count":56,"filter":"raw","cat_ID":22,"category_count":56,"category_description":"","cat_name":"Mode d'emploi","category_nicename":"mode-demploi","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts\/5392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/comments?post=5392"}],"version-history":[{"count":1,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts\/5392\/revisions"}],"predecessor-version":[{"id":5397,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts\/5392\/revisions\/5397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/media\/5333"}],"wp:attachment":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/media?parent=5392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/categories?post=5392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/tags?post=5392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}