{"id":8671,"date":"2024-03-20T16:16:00","date_gmt":"2024-03-20T20:16:00","guid":{"rendered":"https:\/\/copernic.com\/?p=8671"},"modified":"2024-05-03T12:50:06","modified_gmt":"2024-05-03T16:50:06","slug":"utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats","status":"publish","type":"post","link":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/","title":{"rendered":"Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0"},"content":{"rendered":"\n<p>Lorsque vous avez besoin de retrouver un fichier particulier, vous voulez le trouver le plus rapidement possible afin de pouvoir continuer votre journ\u00e9e et de ne pas perdre un temps pr\u00e9cieux \u00e0 fouiller dans un fichier apr\u00e8s l&rsquo;autre.&nbsp; Vous avez sans doute d\u00e9j\u00e0 exp\u00e9riment\u00e9 l&rsquo;efficacit\u00e9 rapide de Desktop &amp; Cloud Search de Copernic. Savoir utiliser les affinements peut rendre votre recherche encore plus rapide.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Dans notre sc\u00e9nario, il vous a \u00e9t\u00e9 demand\u00e9 de compiler toutes les factures de l&rsquo;ann\u00e9e civile. Taper seulement \u00ab facture \u00bb dans la barre de recherche affiche presque 400 r\u00e9sultats. Cela repr\u00e9sente beaucoup de recherche et peut entra\u00eener le risque d&rsquo;inclure des fichiers non valides.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"180\" src=\"https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P1.png\" alt=\"\" class=\"wp-image-8804\" srcset=\"https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P1.png 780w, https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P1-300x69.png 300w, https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P1-768x177.png 768w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/figure>\n\n\n\n<p>C&rsquo;est l\u00e0 que les affinements entrent en jeu! Nous n&rsquo;avons besoin que des factures envoy\u00e9es cette ann\u00e9e. En s\u00e9lectionnant le menu d\u00e9roulant \u00ab Date \u00bb, nous pourrons saisir toutes les informations relatives \u00e0 la date dont nous avons besoin pour affiner les r\u00e9sultats de notre recherche. Dans ce cas, nous avons besoin de tout fichier contenant le mot \u00ab facture \u00bb apr\u00e8s le 31 d\u00e9cembre 2023 :&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"130\" src=\"https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P2.png\" alt=\"\" class=\"wp-image-8806\" srcset=\"https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P2.png 780w, https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P2-300x50.png 300w, https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P2-768x128.png 768w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/figure>\n\n\n\n<p>Cela nous am\u00e8ne \u00e0 23 r\u00e9sultats.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Toutes nos factures sont des PDF. L&rsquo;utilisation du menu d\u00e9roulant \u00ab Type de fichier \u00bb peut nous aider \u00e0 localiser uniquement les PDF contenant le mot \u00ab facture \u00bb dans la p\u00e9riode souhait\u00e9e.&nbsp;&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"238\" src=\"https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P3.png\" alt=\"\" class=\"wp-image-8808\" style=\"width:760px;height:auto\" srcset=\"https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P3.png 780w, https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P3-300x92.png 300w, https:\/\/copernic.com\/wp-content\/uploads\/2024\/05\/P3-768x234.png 768w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque vous avez besoin de retrouver un fichier particulier, vous voulez le trouver le plus rapidement possible afin de pouvoir continuer votre journ\u00e9e et de ne pas perdre un temps pr\u00e9cieux \u00e0 fouiller dans un fichier apr\u00e8s l&rsquo;autre.&nbsp; Vous avez sans doute d\u00e9j\u00e0 exp\u00e9riment\u00e9 l&rsquo;efficacit\u00e9 rapide de Desktop &amp; Cloud Search de Copernic. Savoir utiliser&#8230;<\/p>\n","protected":false},"author":3,"featured_media":8599,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[22,1],"tags":[],"class_list":["post-8671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mode-demploi","category-non-classe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0 | Copernic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0 | Copernic\" \/>\n<meta property=\"og:description\" content=\"Lorsque vous avez besoin de retrouver un fichier particulier, vous voulez le trouver le plus rapidement possible afin de pouvoir continuer votre journ\u00e9e et de ne pas perdre un temps pr\u00e9cieux \u00e0 fouiller dans un fichier apr\u00e8s l&rsquo;autre.&nbsp; Vous avez sans doute d\u00e9j\u00e0 exp\u00e9riment\u00e9 l&rsquo;efficacit\u00e9 rapide de Desktop &amp; Cloud Search de Copernic. Savoir utiliser...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/\" \/>\n<meta property=\"og:site_name\" content=\"Copernic\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-20T20:16:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-03T16:50:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/copernic.com\/wp-content\/uploads\/2024\/03\/File-Type-Refinements.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R\u00f3mulo Oma\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"R\u00f3mulo Oma\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/\"},\"author\":{\"name\":\"R\u00f3mulo Oma\u00f1a\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/person\\\/7985327088d54ba4e291e8dc69713fe6\"},\"headline\":\"Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0\",\"datePublished\":\"2024-03-20T20:16:00+00:00\",\"dateModified\":\"2024-05-03T16:50:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/\"},\"wordCount\":252,\"publisher\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/File-Type-Refinements.jpeg\",\"articleSection\":[\"Mode d'emploi\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/\",\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/\",\"name\":\"Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0 | Copernic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/File-Type-Refinements.jpeg\",\"datePublished\":\"2024-03-20T20:16:00+00:00\",\"dateModified\":\"2024-05-03T16:50:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/#primaryimage\",\"url\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/File-Type-Refinements.jpeg\",\"contentUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/File-Type-Refinements.jpeg\",\"width\":1200,\"height\":900,\"caption\":\"Lucky day. Emotional latin woman celebrating success in front of laptop at cafe, clenching fists, screaming and exclaining with joy. Overjoyed lady working distantly, free space\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2024\\\/03\\\/20\\\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/copernic.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/\",\"name\":\"Copernic\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/copernic.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#organization\",\"name\":\"Copernic\",\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo.png\",\"width\":238,\"height\":68,\"caption\":\"Copernic\"},\"image\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/person\\\/7985327088d54ba4e291e8dc69713fe6\",\"name\":\"R\u00f3mulo Oma\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g\",\"caption\":\"R\u00f3mulo Oma\u00f1a\"},\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/author\\\/romanacopernic-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0 | Copernic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/","og_locale":"fr_CA","og_type":"article","og_title":"Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0 | Copernic","og_description":"Lorsque vous avez besoin de retrouver un fichier particulier, vous voulez le trouver le plus rapidement possible afin de pouvoir continuer votre journ\u00e9e et de ne pas perdre un temps pr\u00e9cieux \u00e0 fouiller dans un fichier apr\u00e8s l&rsquo;autre.&nbsp; Vous avez sans doute d\u00e9j\u00e0 exp\u00e9riment\u00e9 l&rsquo;efficacit\u00e9 rapide de Desktop &amp; Cloud Search de Copernic. Savoir utiliser...","og_url":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/","og_site_name":"Copernic","article_published_time":"2024-03-20T20:16:00+00:00","article_modified_time":"2024-05-03T16:50:06+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/copernic.com\/wp-content\/uploads\/2024\/03\/File-Type-Refinements.jpeg","type":"image\/jpeg"}],"author":"R\u00f3mulo Oma\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"R\u00f3mulo Oma\u00f1a","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/#article","isPartOf":{"@id":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/"},"author":{"name":"R\u00f3mulo Oma\u00f1a","@id":"https:\/\/copernic.com\/fr\/#\/schema\/person\/7985327088d54ba4e291e8dc69713fe6"},"headline":"Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0","datePublished":"2024-03-20T20:16:00+00:00","dateModified":"2024-05-03T16:50:06+00:00","mainEntityOfPage":{"@id":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/"},"wordCount":252,"publisher":{"@id":"https:\/\/copernic.com\/fr\/#organization"},"image":{"@id":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2024\/03\/File-Type-Refinements.jpeg","articleSection":["Mode d'emploi"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/","url":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/","name":"Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0 | Copernic","isPartOf":{"@id":"https:\/\/copernic.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/#primaryimage"},"image":{"@id":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/#primaryimage"},"thumbnailUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2024\/03\/File-Type-Refinements.jpeg","datePublished":"2024-03-20T20:16:00+00:00","dateModified":"2024-05-03T16:50:06+00:00","breadcrumb":{"@id":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/#primaryimage","url":"https:\/\/copernic.com\/wp-content\/uploads\/2024\/03\/File-Type-Refinements.jpeg","contentUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2024\/03\/File-Type-Refinements.jpeg","width":1200,"height":900,"caption":"Lucky day. Emotional latin woman celebrating success in front of laptop at cafe, clenching fists, screaming and exclaining with joy. Overjoyed lady working distantly, free space"},{"@type":"BreadcrumbList","@id":"https:\/\/copernic.com\/fr\/2024\/03\/20\/utilisation-des-affinements-de-date-et-de-type-de-fichier-pour-obtenir-les-meilleurs-resultats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/copernic.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Utilisation des affinements de date et de type de fichier pour obtenir les meilleurs r\u00e9sultats\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/copernic.com\/fr\/#website","url":"https:\/\/copernic.com\/fr\/","name":"Copernic","description":"","publisher":{"@id":"https:\/\/copernic.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/copernic.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/copernic.com\/fr\/#organization","name":"Copernic","url":"https:\/\/copernic.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/copernic.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/12\/logo.png","contentUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/12\/logo.png","width":238,"height":68,"caption":"Copernic"},"image":{"@id":"https:\/\/copernic.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/copernic.com\/fr\/#\/schema\/person\/7985327088d54ba4e291e8dc69713fe6","name":"R\u00f3mulo Oma\u00f1a","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g","caption":"R\u00f3mulo Oma\u00f1a"},"url":"https:\/\/copernic.com\/fr\/author\/romanacopernic-com\/"}]}},"taxonomy_info":{"category":[{"value":22,"label":"Mode d'emploi"},{"value":1,"label":"Non class\u00e9"}]},"featured_image_src_large":["https:\/\/copernic.com\/wp-content\/uploads\/2024\/03\/File-Type-Refinements-1024x768.jpeg",1024,768,true],"author_info":{"display_name":"R\u00f3mulo Oma\u00f1a","author_link":"https:\/\/copernic.com\/fr\/author\/romanacopernic-com\/"},"comment_info":0,"category_info":[{"term_id":22,"name":"Mode d'emploi","slug":"mode-demploi","term_group":0,"term_taxonomy_id":22,"taxonomy":"category","description":"","parent":0,"count":56,"filter":"raw","cat_ID":22,"category_count":56,"category_description":"","cat_name":"Mode d'emploi","category_nicename":"mode-demploi","category_parent":0},{"term_id":1,"name":"Non class\u00e9","slug":"non-classe","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":34,"filter":"raw","cat_ID":1,"category_count":34,"category_description":"","cat_name":"Non class\u00e9","category_nicename":"non-classe","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts\/8671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/comments?post=8671"}],"version-history":[{"count":2,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts\/8671\/revisions"}],"predecessor-version":[{"id":8810,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts\/8671\/revisions\/8810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/media\/8599"}],"wp:attachment":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/media?parent=8671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/categories?post=8671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/tags?post=8671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}