{"id":9572,"date":"2025-02-14T13:26:06","date_gmt":"2025-02-14T18:26:06","guid":{"rendered":"https:\/\/copernic.com\/?p=9572"},"modified":"2025-03-11T13:30:10","modified_gmt":"2025-03-11T17:30:10","slug":"transfert-de-courriel-directement-depuis-copernic","status":"publish","type":"post","link":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/","title":{"rendered":"Transfert de courriel directement depuis Copernic"},"content":{"rendered":"\n<p>Saviez-vous que Copernic vous permet de g\u00e9rer vos courriels directement dans le logiciel ? Lorsqu\u2019il s\u2019est \u00e9coul\u00e9 plusieurs mois depuis la r\u00e9ception de ce courriel tr\u00e8s important\u2122 et que votre \u00e9quipe vous demande de le leur renvoyer, Copernic peut vous aider ! Vos r\u00e9sultats de recherche seront rapides et complets.<\/p>\n\n\n\n<p>Dans notre sc\u00e9nario aujourd\u2019hui, vous devez transf\u00e9rer le courriel concernant la f\u00eate de fin d\u2019ann\u00e9e de l\u2019entreprise. Une recherche rapide du mot \u00ab f\u00eate \u00bb vous indique le nombre de courriels trouv\u00e9s. Cliquez une seule fois sur le courriel qui vous semble \u00eatre le bon. Le volet d\u2019aper\u00e7u situ\u00e9 en dessous vous permettra d\u2019en voir le contenu sans l\u2019ouvrir. Utilisez les nombreux filtres pour affiner davantage vos r\u00e9sultats.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"235\" src=\"https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1.png\" alt=\"\" class=\"wp-image-9573\" srcset=\"https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1.png 720w, https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1-300x98.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p>Compar\u00e9 \u00e0 une recherche du m\u00eame terme uniquement dans Outlook, vous constaterez que plus de 620 documents ont \u00e9t\u00e9 trouv\u00e9s.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"345\" src=\"https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1-1.png\" alt=\"\" class=\"wp-image-9575\" srcset=\"https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1-1.png 720w, https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1-1-300x144.png 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<p>Le menu d\u00e9roulant situ\u00e9 dans le coin sup\u00e9rieur droit du volet d\u2019aper\u00e7u propose une option \u00ab Transf\u00e9rer \u00bb. Double-cliquez sur \u00ab Transf\u00e9rer \u00bb pour ouvrir ce courriel pr\u00eat \u00e0 \u00eatre envoy\u00e9 aux destinataires de votre choix. Vous avez chang\u00e9 d\u2019avis et pr\u00e9f\u00e9rez r\u00e9pondre \u00e0 tous ? Aucun probl\u00e8me. Comme vous pouvez le voir, de nombreuses autres options s\u2019offrent \u00e0 vous.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"362\" height=\"362\" src=\"https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1.jpg\" alt=\"\" class=\"wp-image-9577\" srcset=\"https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1.jpg 362w, https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1-300x300.jpg 300w, https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1-150x150.jpg 150w\" sizes=\"auto, (max-width: 362px) 100vw, 362px\" \/><\/figure>\n\n\n\n<p>Si vous n\u2019avez pas besoin d\u2019utiliser le volet d\u2019aper\u00e7u, vous pouvez \u00e9galement acc\u00e9der aux m\u00eames options en faisant un clic droit sur le courriel que vous souhaitez transf\u00e9rer directement depuis vos r\u00e9sultats.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"362\" height=\"362\" src=\"https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1-1.jpg\" alt=\"\" class=\"wp-image-9579\" srcset=\"https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1-1.jpg 362w, https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1-1-300x300.jpg 300w, https:\/\/copernic.com\/wp-content\/uploads\/2025\/03\/Picture1-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 362px) 100vw, 362px\" \/><\/figure>\n\n\n\n<p><a href=\"https:\/\/copernicsearch.freshdesk.com\/fr\/support\/discussions\/forums\/47000096845\">Parcourez nos forums<\/a> pour d\u00e9couvrir d\u2019autres astuces et conseils \u00e9prouv\u00e9s ! Vous avez des questions ? Notre \u00e9quipe de support se fera un plaisir de vous aider \u00e0 l\u2019adresse <a href=\"mailto:support@copernic.com\">support@copernic.com<\/a>.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saviez-vous que Copernic vous permet de g\u00e9rer vos courriels directement dans le logiciel ? Lorsqu\u2019il s\u2019est \u00e9coul\u00e9 plusieurs mois depuis la r\u00e9ception de ce courriel tr\u00e8s important\u2122 et que votre \u00e9quipe vous demande de le leur renvoyer, Copernic peut vous aider ! Vos r\u00e9sultats de recherche seront rapides et complets. Dans notre sc\u00e9nario aujourd\u2019hui, vous&#8230;<\/p>\n","protected":false},"author":3,"featured_media":9541,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-9572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transfert de courriel directement depuis Copernic | Copernic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transfert de courriel directement depuis Copernic | Copernic\" \/>\n<meta property=\"og:description\" content=\"Saviez-vous que Copernic vous permet de g\u00e9rer vos courriels directement dans le logiciel ? Lorsqu\u2019il s\u2019est \u00e9coul\u00e9 plusieurs mois depuis la r\u00e9ception de ce courriel tr\u00e8s important\u2122 et que votre \u00e9quipe vous demande de le leur renvoyer, Copernic peut vous aider ! Vos r\u00e9sultats de recherche seront rapides et complets. Dans notre sc\u00e9nario aujourd\u2019hui, vous...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/\" \/>\n<meta property=\"og:site_name\" content=\"Copernic\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-14T18:26:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-11T17:30:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/copernic.com\/wp-content\/uploads\/2025\/02\/Forwarding-Email.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"979\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"R\u00f3mulo Oma\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"R\u00f3mulo Oma\u00f1a\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/\"},\"author\":{\"name\":\"R\u00f3mulo Oma\u00f1a\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/person\\\/7985327088d54ba4e291e8dc69713fe6\"},\"headline\":\"Transfert de courriel directement depuis Copernic\",\"datePublished\":\"2025-02-14T18:26:06+00:00\",\"dateModified\":\"2025-03-11T17:30:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/\"},\"wordCount\":298,\"publisher\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Forwarding-Email.jpeg\",\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/\",\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/\",\"name\":\"Transfert de courriel directement depuis Copernic | Copernic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Forwarding-Email.jpeg\",\"datePublished\":\"2025-02-14T18:26:06+00:00\",\"dateModified\":\"2025-03-11T17:30:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Forwarding-Email.jpeg\",\"contentUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Forwarding-Email.jpeg\",\"width\":1500,\"height\":979,\"caption\":\"Mail Communication Connection message to mailing contacts phone Global Letters Concept\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/2025\\\/02\\\/14\\\/transfert-de-courriel-directement-depuis-copernic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/copernic.com\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transfert de courriel directement depuis Copernic\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/\",\"name\":\"Copernic\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/copernic.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#organization\",\"name\":\"Copernic\",\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/copernic.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/logo.png\",\"width\":238,\"height\":68,\"caption\":\"Copernic\"},\"image\":{\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/copernic.com\\\/fr\\\/#\\\/schema\\\/person\\\/7985327088d54ba4e291e8dc69713fe6\",\"name\":\"R\u00f3mulo Oma\u00f1a\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g\",\"caption\":\"R\u00f3mulo Oma\u00f1a\"},\"url\":\"https:\\\/\\\/copernic.com\\\/fr\\\/author\\\/romanacopernic-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transfert de courriel directement depuis Copernic | Copernic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/","og_locale":"fr_CA","og_type":"article","og_title":"Transfert de courriel directement depuis Copernic | Copernic","og_description":"Saviez-vous que Copernic vous permet de g\u00e9rer vos courriels directement dans le logiciel ? Lorsqu\u2019il s\u2019est \u00e9coul\u00e9 plusieurs mois depuis la r\u00e9ception de ce courriel tr\u00e8s important\u2122 et que votre \u00e9quipe vous demande de le leur renvoyer, Copernic peut vous aider ! Vos r\u00e9sultats de recherche seront rapides et complets. Dans notre sc\u00e9nario aujourd\u2019hui, vous...","og_url":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/","og_site_name":"Copernic","article_published_time":"2025-02-14T18:26:06+00:00","article_modified_time":"2025-03-11T17:30:10+00:00","og_image":[{"width":1500,"height":979,"url":"https:\/\/copernic.com\/wp-content\/uploads\/2025\/02\/Forwarding-Email.jpeg","type":"image\/jpeg"}],"author":"R\u00f3mulo Oma\u00f1a","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"R\u00f3mulo Oma\u00f1a","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/#article","isPartOf":{"@id":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/"},"author":{"name":"R\u00f3mulo Oma\u00f1a","@id":"https:\/\/copernic.com\/fr\/#\/schema\/person\/7985327088d54ba4e291e8dc69713fe6"},"headline":"Transfert de courriel directement depuis Copernic","datePublished":"2025-02-14T18:26:06+00:00","dateModified":"2025-03-11T17:30:10+00:00","mainEntityOfPage":{"@id":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/"},"wordCount":298,"publisher":{"@id":"https:\/\/copernic.com\/fr\/#organization"},"image":{"@id":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/#primaryimage"},"thumbnailUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2025\/02\/Forwarding-Email.jpeg","articleSection":["Non classifi\u00e9(e)"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/","url":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/","name":"Transfert de courriel directement depuis Copernic | Copernic","isPartOf":{"@id":"https:\/\/copernic.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/#primaryimage"},"image":{"@id":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/#primaryimage"},"thumbnailUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2025\/02\/Forwarding-Email.jpeg","datePublished":"2025-02-14T18:26:06+00:00","dateModified":"2025-03-11T17:30:10+00:00","breadcrumb":{"@id":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/#primaryimage","url":"https:\/\/copernic.com\/wp-content\/uploads\/2025\/02\/Forwarding-Email.jpeg","contentUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2025\/02\/Forwarding-Email.jpeg","width":1500,"height":979,"caption":"Mail Communication Connection message to mailing contacts phone Global Letters Concept"},{"@type":"BreadcrumbList","@id":"https:\/\/copernic.com\/fr\/2025\/02\/14\/transfert-de-courriel-directement-depuis-copernic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/copernic.com\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Transfert de courriel directement depuis Copernic"}]},{"@type":"WebSite","@id":"https:\/\/copernic.com\/fr\/#website","url":"https:\/\/copernic.com\/fr\/","name":"Copernic","description":"","publisher":{"@id":"https:\/\/copernic.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/copernic.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/copernic.com\/fr\/#organization","name":"Copernic","url":"https:\/\/copernic.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/copernic.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/12\/logo.png","contentUrl":"https:\/\/copernic.com\/wp-content\/uploads\/2023\/12\/logo.png","width":238,"height":68,"caption":"Copernic"},"image":{"@id":"https:\/\/copernic.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/copernic.com\/fr\/#\/schema\/person\/7985327088d54ba4e291e8dc69713fe6","name":"R\u00f3mulo Oma\u00f1a","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b93370bd7adbfe5b91bc60132a570bee368d94f76e8b2f04bf5c7ef5a0343645?s=96&d=mm&r=g","caption":"R\u00f3mulo Oma\u00f1a"},"url":"https:\/\/copernic.com\/fr\/author\/romanacopernic-com\/"}]}},"taxonomy_info":{"category":[{"value":7,"label":"Non classifi\u00e9(e)"}]},"featured_image_src_large":["https:\/\/copernic.com\/wp-content\/uploads\/2025\/02\/Forwarding-Email-1024x668.jpeg",1024,668,true],"author_info":{"display_name":"R\u00f3mulo Oma\u00f1a","author_link":"https:\/\/copernic.com\/fr\/author\/romanacopernic-com\/"},"comment_info":0,"category_info":[{"term_id":7,"name":"Non classifi\u00e9(e)","slug":"non-classifiee","term_group":0,"term_taxonomy_id":7,"taxonomy":"category","description":"","parent":0,"count":8,"filter":"raw","cat_ID":7,"category_count":8,"category_description":"","cat_name":"Non classifi\u00e9(e)","category_nicename":"non-classifiee","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts\/9572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/comments?post=9572"}],"version-history":[{"count":1,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts\/9572\/revisions"}],"predecessor-version":[{"id":9581,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/posts\/9572\/revisions\/9581"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/media\/9541"}],"wp:attachment":[{"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/media?parent=9572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/categories?post=9572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/copernic.com\/fr\/wp-json\/wp\/v2\/tags?post=9572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}